{"text_format":"1","workbook":"xlsx","n_sheets":5,"sheets":["Front Cover","User Guide","Main sheet - Receptor Risk","Dropdown lists","Ranking matrix"],"not_rendered":{"charts":0,"images":22,"macros":1,"external_links":0,"defined_names":104,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Front Cover","index":0,"n_rows":73,"n_cols":1,"rows_kept":73,"cut":false,"hidden":false,"merged":[[42,0,42,8],[44,0,44,8],[53,0,53,8],[58,0,58,8],[72,0,72,8]]}
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["This spreadsheet tool provides the user with a decision support platform designed by the Joint Industry Working Group for Asbestos in Soil and Construction & Demolition Materials (JIWG) to assist in the risk-rank activities and receptors as part of a preliminary risk assessment under CLR11.  The aim of developing this tool is to provide industry with a consistent decision making format that is aligned with UK health & safety and environmental regulatory policies, and is consistent with the wider objectives of the JIWG."]
[]
["This is Version 2 of this tool, and has been amended following industry feedback on the BETA version released in 2016.  The JIWG would welcome feedback from users of this version on its applicability and validity to the wide range of scenarios that may be encountered when assessing the potential risk from asbestos and asbestos-containing materials in the ground."]
[]
[]
["ISBN 978-1-905046-29-4"]
[]
["© CL:AIRE 2017"]
[]
["Published by CL:AIRE, 32 Bloomsbury Street, London WC1B 3QJ."]
[]
["All rights reserved.  No part of this publication or tool may be reproduced, stored in a retrieval system, or transmitted in any form or by any other means, electronic, mechanical, photocopying, recording or otherwise, without the written permission of the copyright holder."]
[]
[]
["Acknowledgements"]
[]
["CL:AIRE and the JIWG would like to gratefully acknowledge Simon Cole - AECOM, Stephen Forster - Remedia Group and Garry Burdett - Health and Safety Laboratory for the design and development of this decision support tool."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Disclaimer"]
[]
["CL:AIRE and the JIWG will not be responsible for any loss, however arising, the use of, or reliance on, the information contained in this decision support tool and associated user guide, nor do they assume responsibility or liability for errors or omissions contained within.  Users are advised to use the information contained herein purely as a guide and to take appropriate professional advice where necessary."]

{"sheet":"User Guide","index":1,"n_rows":370,"n_cols":2,"rows_kept":370,"cut":false,"hidden":false,"merged":[[131,1,131,13],[6,1,7,14],[9,1,39,14],[41,1,41,14],[42,1,42,14],[43,1,43,14],[44,1,44,14],[46,1,46,14],[69,1,69,14],[87,1,87,13],[102,1,102,14],[117,1,117,13],[213,1,213,14],[228,1,228,14],[230,1,230,14],[232,1,232,14],[233,1,233,14],[145,1,145,14],[55,1,55,14],[333,1,333,14],[353,1,353,14],[369,1,369,14],[310,1,310,14],[270,1,270,14],[290,1,290,14],[315,1,315,14],[321,1,321,14],[308,1,308,14],[251,1,251,14],[150,1,150,14],[165,1,165,14],[181,1,181,14],[197,1,197,14]]}
[]
[]
[]
[]
[]
[]
[null,"Decision Support Tools for the Qualitative Risk Ranking of Work Activities and Receptors Involved in or Exposed to Asbestos in Soil or Construction & Demolition Materials"]
[]
[]
[null,"This spreadsheet tool provides the user with a decision support platform designed by the Joint Industry Working Group to assist in the risk-rank activities and receptors as part of a preliminary risk assessment under CLR11.  The spreadsheet should be used by  competent persons and does not replace the sound professional judgement of a competent person.\n\nThe aim of developing this tool is to provide industry with a consistent decision making format that is aligned with UK health & safety and environmental regulatory policies, and is consistent with the wider objectives of the JIWG.\n\nThe hazard and risk ranking approaches take influences from the HSG227 material and priority scoring systems and the R&D66 qualitative risk assessment methods and identifies key hazard and risk factors that are relevant to the management of risk from exposure to asbestos contaminated soils, made ground or construction & demolition materials.  By doing so, this tool is designed to support Stage 2 and Stage 3 of SoBRA’s Conceptual Framework for Asbestos Risk Assessment & Control (April 2015) freely available via www.sobra.org.uk.\n\nThe spreadsheet is designed to lead the user through a series of options for each identified factor.  These factors are grouped into Stages with each stage providing a numerical and/or qualitative hazard or risk ranking phrase.  The user is lead sequentially through each Stage with the stages ordered from left to right.  A step by step guide to each stage is provided below:\n\nGeneral points:\n\nAlways choose the dropdown option that best fits your understanding of factor under consideration.  If one option does not sufficiently reflect the dominant situation on-site re-run the DST using the most applicable options sequentially. Always use a new version of the spreadsheet if you want to save multiple versions.  Don't copy and insert the Main sheet as a new tab as the functionality of the spreadsheet may be compromised by the copying process.\n\nThe spreadsheet works on a fixed logic basis.  No guarantee is made that the spreadsheet will output the \"correct\" answer 100% of the time.  The output should always be reviewed by a competent person to check that the choice of inputs and resultant risk ranking scores output by the DST make sense.\n\nAcknowledgements:\n\nDST developers: Simon Cole - AECOM, Garry Burdett - Health & Safety Laboratory, Stephen Forster - Remedia Group"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"No warranty, expressed or implied, or reliance, is provided in relation to the use of this tool."]
[null,"It is contingent on users to satisfy themselves that the output from the tool is relevant and appropriate to the assessment being made."]
[null,"This tool has been developed and is made freely available by the JIWG."]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Decision Support Tool for Receptor Risk Ranking"]
[]
[null,"Stage 1 - Hazard Factors"]
[null,"These five factors are designed to identify at a basic level the inherent hazard of the asbestos content of the ground or stockpiled material."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 1 - Select ACM type (run model for each plausible type to generate \"Worst Case\" output)"]
[null,"A choice of eight categories to identify, sequentially, the principal ACM types present and designed to distinguish between the groups of ACMs that have clearly different hazard characteristics.  If more than one type of ACM material is present, the DST should be run for each material.  A comparative analysis can then be done on the respective outputs for the worst and best case scenarios.\n\nNB refer to CAR-SOILTM for guidance on differentiation of clearly identifiable insulation, lagging and AIB from unspecified fibrous board and loose fibrous asbestos debris."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 2 - Extent of degradation of ACMs"]
[null,"Four choices to describe the degree of degradation of the ACM at the outset of work to be carried out on the contaminated material.  Note that current HSE guidance suggests that even if the ACMs have been broken up into discernible fragments, this does not necessarily mean that the material is degraded, rather it is the condition of those fragments that determine the degree of degradation.  This dropdown list is conditioned based on the choice of ACM type selected for factor 1."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 3 - Friability and degree of bonding by matrix (ACM matrix, not ground materials)"]
[null,"Three choices to describe the friability of the ACM and the degree of bonding of asbestos fibres in the host matrix.  A material is either friable or non-friable.  \nIf the material is friable, the asbestos fibres will either be not firmly linked in the host ACM matrix, OR, in the case of free dispersed fibres, those fibres will not be firmly linked in any ground material matrix.\nThis dropdown list is conditioned based on the choices for factors 1 and 2."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 4 - Distribution of visible asbestos across affected area"]
[null,"Five qualitative descriptions designed to account for the relative amount of visible ACM contamination present over a site, or within a zone on a site, based on field observations.  This is not necessarily an indication of the mass concentration of asbestos present in the ground matrix.  NB if a material is described as coatings, or clearly identifiable insulation, lagging or AIB, it must be, by definition, visible."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 5 - Asbestos fibre type"]
[null,"Provides the ability to categorise the contamination weighted by asbestos fibre type, either for chrysotile alone, amphibole with our without chrysotile, mixtures of amphibole and chrysotile with crocidolite or crocidolite alone."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Hazard Ranking - provides a qualitative ranking from very low to high dependent on the cumulative score for hazard factors 1-5."]
[]
[]
[]
[null,"Stage 2 - Exposure Factors"]
[null,"These four factors are designed to identify the potential for fibre release and airborne exposure.  These factors are independent of the Hazard Factors in Stage 1 with the exception of the anticipated respirable fibre index - which intentionally builds on factor choices at Stage 1.  Note that host material moisture content is not included in the list of factors considered.  This is an emission mitigating factor that is temporally variable and the effect of host material moisture content should be considered in the interpretation of the final DST ranking."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 1 - Amount of asbestos fibre in selected ACM/fibre type as % of host material"]
[null,"Qualitative descriptions linked to banded quantitative estimates of the weight percentage of asbestos fibre present in the host material.  The host material in this instance is the soil or made ground the asbestos is in.  The concentration estimate relates to the average concentration that best represents the area/volume of soil that may be disturbed.  Care needs to be taken in interpreting laboratory results from small discrete samples if sampling error is poorly understood."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 2 - Respirable fibre index for source material"]
[null,"Use the guidance provided in CIRIA C733 or the original evaluation for the approximation of respirable fibre content in different ACMs provided in RIVM report 711701034 (2003).  Alternatively use available respirable fibre concentrations measured in accordance with the SCA Blue Book Method.  This provides an additional layer of exposure characterisation by adjusting the bulk ACM concentration for the proportion of respirable fibres - those fibres that are most relevant to the exposure hazard."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 3 - Activity type and effect on deterioration of ACMs"]
[null,"Five choices designed to distinguish between activities likely to cause no/minimal deterioration of the ACMs and those that are likely to cause deterioration.   "]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 4 - Best description of primary host material matrix"]
[null,"Six choices for the best description of host material that distinguish between the potential dustiness of that material and the potential for fibre release upon disturbance of that material.  For natural soils (topsoil or subsoil) choose the silt, clay or sand option that best fits the approximate soil particle size distribution."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Exposure ranking - provides a qualitative ranking from very low to high dependent on the cumulative score for emission factors 1-4."]
[]
[]
[null,"Stage 3 - Pathway and Receptor Sensitivity"]
[null,"These four factors are designed to rank the key pathway and receptor characteristics that influence exposure risk.  One factor is not scored - the receptor category choice is merely there to inform the subsequent choices for site occupancy and receptor age."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 1 - Receptor category"]
[]
[null,"Four options designed to distinguish between broad generic land-uses.  The four category choices are provided to guide the subsequent choice of site occupancy and receptor age factors.  The choices cover three standard land-uses and a choice for construction/ground investigation to specifically identify occupational activities associated with ground or stockpiled material disturbance.  The categories are only a guide and therefore the list is not exhaustive."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 2 - Age of receptor"]
[null,"Five choices designed to account for the additional risk created by early years exposure.  Refer to CIRIA C733 Table 14.2 and the committee papers for WATCH held on the HSE website for further information on age adjustment factors."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 3 - Duration of exposure/site occupancy"]
[]
[null,"A choice of five semi-quantitative exposure duration and exposure frequency combinations designed to distinguish between the resultant cumulative exposure.  The choices are independent of the choice of receptor category but should be consistent with exposure activity being considered in relation to that receptor category."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Receptor ranking - provides a qualitative ranking from very low to high dependent on the cumulative score for receptor factors 2-3."]
[]
[null,"Combined hazard, exposure and receptor ranking - provides an additional qualitative ranking from very low to high based on the combination of the hazard, emission and receptor rankings."]
[]
[]
[null,"Factor 4 - Distance from source of dispersion"]
[]
[null,"Four options designed to reflect the typical way in which dust disperses with distance from the source of a fugitive emission.  Based on the evidence provided in RIVM report 711701023 (2003) the distance cut-off is 100m for negligible concentrations."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Factor 5 - Depth to impacted material"]
[]
[null,"Five options designed to reflect the likelihood of disturbance and potential release of fibres to air"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Pathway ranking - provides a qualitative ranking from very low to high dependent on the scores for the two pathway factors using the scoring matrix below."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Overall ranking - provides a qualitative overall scenario ranking from very low to high dependent on the combined hazard, exposure and receptor ranking, and the combined pathway ranking , using the scoring matrix below."]

{"sheet":"Main sheet - Receptor Risk","index":2,"n_rows":45,"n_cols":31,"rows_kept":45,"cut":false,"hidden":false,"merged":[[10,25,11,25],[10,26,11,30],[18,25,19,25],[18,26,19,30],[16,26,16,30],[17,26,17,30],[13,26,13,30],[14,26,14,30],[29,2,30,4],[29,9,30,13],[33,17,34,20],[28,25,34,25],[21,26,26,30],[28,26,34,30],[21,25,26,25]]}
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Decision Support Tool for Receptor Risk Ranking"]
[]
[null,null,"Stage 1",null,null,null,null,null,null,"Stage 2",null,null,null,null,null,null,null,"Stage 3",null,null,null,null,null,null,null,"Project Reference"]
[null,null,"Hazard Identification",null,"Score",null,null,null,null,"Emission Factors",null,"Score",null,null,null,null,null,"Pathway and Receptor Sensitivity",null,"Score"]
[]
[null,null,"Select ACM type (run model for each type to generate 'Worst Case' output)","Woven textiles, string, rope, paper, felt, gaskets etc.",{"$f":"VLOOKUP(Receptor_ACM_Type,LookupTable_ACM_Type,2,FALSE)","v":1},null,null,null,null,"Amount of asbestos fibre in selected ACM/fibre type as % of host material","Low quantities - >0.01 to <0.05 %wt/wt",{"$f":"VLOOKUP(Receptor_Amount,LookupTable_Amount,2,FALSE)","v":2},null,null,null,null,null,"Receptor category","Residential","No score required",null,null,null,null,null,"Site Name"]
[null,null,"Extent of degradation of ACMs","Degraded (Significant degradation in ACM; material has lost its basic integrity)",{"$f":"VLOOKUP(Receptor_Degradation,LookupTable_Degradation_Extent,2,FALSE)","v":3},null,null,null,null,"Respirable fibre index for ACM - RIVM report 711701034 (2003) ","Negligible",{"$f":"VLOOKUP(Receptor_Respirable_Fibre_Index,LookupTable_Respirable_Fibre_Index,2,FALSE)","v":0},null,null,null,null,null,"Age of Receptor","Young adult (>16 and <24)",{"$f":"VLOOKUP(Receptor_Age,LookupTable_Age,2,FALSE)","v":2},null,null,null,null,null,"Client"]
[null,null,"Friability and degree of bonding by matrix (ACM matrix, not ground materials)","Friable ACM or ACM with fibres not linked in any matrix (free dispersed fibres/fibre bundles)",{"$f":"VLOOKUP(Receptor_Friabilty,LookupTable_Friability,2,FALSE)","v":4},null,null,null,null,"Activity type and effect on deterioration of ACMs","High disturbance, significant deterioration expected",{"$f":"VLOOKUP(Receptor_Activity_Type,LookupTable_Activity_Type,2,FALSE)","v":4},null,null,null,null,null,"Duration of exposure/site occupancy","< 1 hour in any single day (e.g. frequent but short exposure event)",{"$f":"VLOOKUP(Receptor_Site_Exposure,LookupTable_Exposure,2,FALSE)","v":1}]
[null,null,"Distribution of Visible Asbestos Across Affected Area","No visible ACMs/fibre bundles",{"$f":"VLOOKUP(Receptor_Asbestos_Distribution,LookupTable_Asbestos_Distribution,2,FALSE)","v":0},null,null,null,null,"Best description of primary host material matrix","Fine Silt and/or Clay",{"$f":"VLOOKUP(Receptor_Host_Material,LookupTable_Host_Material,2,FALSE)","v":1},null,null,null,null,null,null,null,null,null,null,null,null,null,"Run by"]
[null,null,"Asbestos fibre type","Crocidolite alone",{"$f":"VLOOKUP(Receptor_Asb_Type,LookupTable_Asbestos_Type,2,FALSE)","v":4},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Receptor ranking",null,{"$f":"SUM(T15:T16)","v":3},{"$f":"IF(Receptor_Stage3_Subtot>=7,\"High\",IF(Receptor_Stage3_Subtot>=5,\"Medium\",IF(Receptor_Stage3_Subtot>=3,\"Low\",IF(Receptor_Stage3_Subtot<=2,\"Very Low\"))))","v":"Low"},{"$f":"VLOOKUP(Receptor_Rank,'Ranking matrix'!F11:H14,3,FALSE)","v":2},null,null,null,"Reviewed by"]
[null,null,"Sub-total",null,{"$f":"SUM(E14:E18)","v":12},null,null,null,null,"Sub-total",null,{"$f":"SUM(L14:L17)","v":7}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Combined hazard, exposure and receptor ranking",null,{"$f":"SUM(F24,N23,V19)","v":7},{"$f":"IF(Receptor_Combined_Score>=11,\"High\",IF(Receptor_Combined_Score>=8,\"Medium\",IF(Receptor_Combined_Score>=5,\"Low\",IF(Receptor_Combined_Score<=4,\"Very Low\"))))","v":"Low"},{"$f":"VLOOKUP(Receptor_Combined_Rank,'Ranking matrix'!F11:H14, 2, FALSE)","v":"B"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Characterisation of scenario being evaluated"]
[null,null,null,null,null,null,null,null,null,"Exposure ranking",null,null,{"$f":"IF(Receptor_Stage2_SubTot>=15,\"High\",IF(Receptor_Stage2_SubTot>=10,\"Medium\",IF(Receptor_Stage2_SubTot>=5,\"Low\",IF(Receptor_Stage2_SubTot<=4,\"Very Low\"))))","v":"Low"},{"$f":"VLOOKUP(Receptor_Exposure_Rank,'Ranking matrix'!F11:H14,3,FALSE)","v":2},null,null,null,"Pathway: Distance of Receptor from Source","In or within 10m of area of disturbance",{"$f":"VLOOKUP(Receptor_Distance,LookupTable_Distance,2,FALSE)","v":4}]
[null,null,"Hazard ranking",null,{"$f":"IF(Receptor_Stage1_SubTot>=16,\"High\",IF(Receptor_Stage1_SubTot>=11,\"Medium\",IF(Receptor_Stage1_SubTot>=6,\"Low\",IF(Receptor_Stage1_SubTot<=5,\"Very Low\"))))","v":"Medium"},{"$f":"VLOOKUP(Receptor_Stage1_Haz_Rank,'Ranking matrix'!F11:H14,3,FALSE)","v":3},null,null,null,null,null,null,null,null,null,null,null,"Pathway: Depth to impacted material","Material buried at depth, unlikely to be disturbed except for deeper construction related excavation",{"$f":"VLOOKUP(Receptor_Depth,LookupTable_Depth,2,FALSE)","v":"B"}]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pathway ranking",null,{"$f":"CONCATENATE(T23,T24)","v":"4B"},{"$f":"VLOOKUP(T26,'Ranking matrix'!J11:K30,2,FALSE)","v":"Very Low"},{"$f":"VLOOKUP(U26,'Ranking matrix'!F16:GH20,3,FALSE)","v":2}]
[null,"No warranty, expressed or implied, or reliance, is provided in relation to the use of this tool. \n"]
[null,"It is contingent on users to satisfy themselves that the output from the tool is relevant and appropriate to the assessment being made.",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"CONCATENATE(V26,V21)","v":"2B"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Interpretation of scenario ranking by DST"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Overall ranking",null,null,{"$f":"VLOOKUP(U28,'Ranking matrix'!C11:D30,2,FALSE)","v":"Negligible"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["© Joint Industry Working Group, ©CL:AIRE",null,null,null,null,"Page 1 of 4",null,"© Joint Industry Working Group, ©CL:AIRE",null,null,null,null,null,"Page 2 of 4",null,"© Joint Industry Working Group, ©CL:AIRE",null,null,null,null,null,"Page 3 of 4",null,"© Joint Industry Working Group, ©CL:AIRE",null,null,null,null,null,null,"Page 4 of 4"]
["Version 2, February 2017",null,null,null,null,null,null,"Version 2, February 2017",null,null,null,null,null,null,null,"Version 2, February 2017",null,null,null,null,null,null,null,"Version 2, February 2017"]

{"sheet":"Dropdown lists","index":3,"n_rows":36,"n_cols":9,"rows_kept":36,"cut":false,"hidden":true,"merged":[]}
[]
[null,"Select ACM type (run model for each type to generate 'Worst Case' output)",null,null,"Amount of asbestos fibre in selected ACM/fibre type as % of host material",null,null,"Receptor Category"]
[null,"Bonded ACMs: cement, vinyl, composites,  textured decorative coatings, bitumen products",0,null,"Trace quantities - <0.0001 to <0.001 %wt/wt",0,null,"Commercial/industrial",1]
[null,"Woven textiles, string, rope, paper, felt, gaskets etc.",1,null,"Very Low quantities - 0.001 to 0.01 %wt/wt",1,null,"Construction",2]
[null,"Unspecified fibrous board",2,null,"Low quantities - >0.01 to <0.05 %wt/wt",2,null,"Public open space or building",3]
[null,"Free dispersed fibres/fibre bundles",2,null,"Moderate quantities - 0.05 to <0.1 %wt/wt",3,null,"Residential",4]
[null,"Clearly identifiable insulating board",2,null,"Large quantities - ≥0.1 %wt/wt",4]
[null,"Loose fibrous asbestos debris",3,null,null,null,null,"Receptor age"]
[null,"Clearly identifiable insulation or lagging",3,null,"Respirable fibre index - RIVM",null,null,"Adult (>60)",0]
[null,"Coatings (excluding textured decorative coatings)",4,null,"Negligible",0,null,"Adult (>24 and <60)",1]
[null,null,null,null,"Very low",1,null,"Young adult (>16 and <24)",2]
[null,"Extent of degradation of ACMs",null,null,"Low",2,null,"School age (>5 and <16)",3]
[null,"Intact (Very good condition ACM/ACM fragments",1,null,"Medium",3,null,"Infant (under 5)",4]
[null,"Weathered (Slight degradation in ACM; material still retains its basic integrity)",2,null,"High",4]
[null,"Degraded (Significant degradation in ACM; material has lost its basic integrity)",3,null,null,null,null,"Exposure frequency and duration"]
[null,"Disaggregated (dominated by loose fibrous material; extreme degradation in ACM and/or free asbestos fibres/fibre bundles)",4,null,"Activity type and effect on deterioration of ACMs during use of site",null,null,"<1 hour in any week (e.g. short duration work or equivalent infrequent exposure event when exposure aggregated over 1 yr)",0]
[null,null,null,null,"No disturbance activity",0,null,"< 1 hour in any single day (e.g. frequent but short exposure event)",1]
[null,"Friability and degree of bonding by matrix (refers to ACM matrix)",null,null,"Minimal disturbance, no deterioration expected",1,null,"> 1hr <10 hr daily exposure (e.g. part-time to full time occupational exposure or extended daily recreational exposure)",3]
[null,"Non-friable ACM or ACM with fibres firmly linked in a matrix",0,null,"Low disturbance, minimal deterioration expected",2,null,">> 10 hours per day (e.g. 24 hour residential exposure)",4]
[null,"Friable ACM or ACM with fibres not firmly linked in a matrix",2,null,"Moderate disturbance, slight deterioration expected",3]
[null,"Friable ACM or ACM with fibres not linked in any matrix (free dispersed fibres/fibre bundles)",4,null,"High disturbance, significant deterioration expected",4,null,"Distance from source (m)"]
[null,null,null,null,null,null,null,">100m distance from edge of area of disturbance",1]
[null,null,null,null,"Best description of primary host material matrix",null,null,">50m distance from edge of area of disturbance",2]
[null,"Distribution of Visible Asbestos Across Affected Area",null,null,"Fine Silt and/or Clay",1,null,">10m of edge of area of disturbance",3]
[null,"No visible ACMs/fibre bundles",0,null,"Coarse to Fine Sand",2,null,"In or within 10m of area of disturbance",4]
[null,"Occasional/random occurrences of visible contamination by ACMs",1,null,"Coarse to Fine Gravel",3]
[null,"Sporadic/random occurrences of visible contamination by ACMs",2,null,"Naturally occurring rock, stone (crushed or not)",4,null,"Depth to impacted material"]
[null,"Moderate/frequent occurrences of visible contamination by ACMs",3,null,"Ceramics - Concrete, Bricks, Mortar, Tiles, Clayware (crushed or not)",4,null,"Material buried at significant depth, very unlikely to be disturbed.","A"]
[null,"Gross/very frequent occurrences of visible contamination by ACMs",4,null,"Made Ground - Recycled Aggregate, Track Ballast",4,null,"Material buried at depth, unlikely to be disturbed except for deeper construction related excavation","B"]
[null,null,null,null,null,null,null,"Material buried at shallow depth, potential to be disturbed by excavation","C"]
[null,"Asbestos fibre type",null,null,null,null,null,"Material present near the surface, potential to be disturbed during non-construction/routine use of land","D"]
[null,"Chrysotile alone",0,null,null,null,null,"Material visible at the surface, very likely to be disturbed by wind erosion and/or human/animal disturbance of soil surface","E"]
[null,"Mainly chrysotile and trace amphibole (no crocidolite)",1]
[null,"Mainly amphibole and chrysotile mixtures, including trace crocidolite",2]
[null,"Mainly amosite (and possible trace tremolite/anthophyllite) with/without chrysotile (no crocidolite)",3]
[null,"Crocidolite alone",4]

{"sheet":"Ranking matrix","index":4,"n_rows":53,"n_cols":14,"rows_kept":53,"cut":false,"hidden":true,"merged":[[3,0,6,0],[0,2,0,6],[0,9,0,12]]}
[null,null,"Combined Pathway Ranking",null,null,null,null,null,null,"Distance from source"]
[null,null,"Negligible","Very Low","Low","Medium","High",null,null,">100m","<100m","<50m","<10m"]
[null,null,1,2,3,4,5,null,null,1,2,3,4]
["Combined hazard, exposure, receptor ranking","Very Low","Negligible","Negligible","Negligible","Very Low","Low","A","Material buried at significant depth, very unlikely to be disturbed.","Negligible","Negligible","Negligible","Negligible","A"]
[null,"Low","Negligible","Negligible","Very Low","Low","Medium","B","Material buried at depth, unlikely to be disturbed except for deeper construction related excavation","Negligible","Negligible","Very Low","Very Low","B"]
[null,"Medium","Negligible","Very Low","Low","Medium","High","C","Material buried at shallow depth, potential to be disturbed by excavation","Negligible","Very Low","Low","Low","C"]
[null,"High","Very Low","Low","Medium","High","High","D","Material present near the surface, potential to be disturbed during non-construction/routine use of land","Very Low","Low","Low","Medium","D"]
[null,null,null,null,null,null,null,null,"Material visible at the surface, very likely to be disturbed by wind erosion and/or human/animal disturbance of soil surface","Very Low","Low","Medium","High","E"]
[]
[]
[null,null,"1A","Negligible",null,"Very Low","A",1,null,"1A","Negligible"]
[null,null,"1B","Negligible",null,"Low","B",2,null,"1B","Negligible"]
[null,null,"1C","Negligible",null,"Medium","C",3,"`","1C","Negligible"]
[null,null,"1D","Very Low",null,"High","D",4,null,"1D","Very Low"]
[null,null,"2A","Negligible",null,null,null,null,null,"1E","Very Low"]
[null,null,"2B","Negligible",null,"Negligible","A",1,null,"2A","Negligible"]
[null,null,"2C","Very Low",null,"Very Low","B",2,null,"2B","Negligible"]
[null,null,"2D","Low",null,"Low","C",3,null,"2C","Very Low"]
[null,null,"3A","Negligible",null,"Medium","D",4,null,"2D","Low"]
[null,null,"3B","Very Low",null,"High","E",5,null,"2E","Low"]
[null,null,"3C","Low",null,null,null,null,null,"3A","Negligible"]
[null,null,"3D","Medium",null,null,null,null,null,"3B","Very Low"]
[null,null,"4A","Very Low",null,null,null,null,null,"3C","Low"]
[null,null,"4B","Low",null,null,null,null,null,"3D","Low"]
[null,null,"4C","Medium",null,null,null,null,null,"3E","Medium"]
[null,null,"4D","High",null,null,null,null,null,"4A","Negligible"]
[null,null,"5A","Low",null,null,null,null,null,"4B","Very Low"]
[null,null,"5B","Medium",null,null,null,null,null,"4C","Low"]
[null,null,"5C","High",null,null,null,null,null,"4D","Medium"]
[null,null,"5D","High",null,null,null,null,null,"4E","High"]
[]
[]
[null,null,"Stage 1",null,"Stage 2",null,"Stage 3A","Stage 3B"]
[null,null,1,null,1,null,1,1]
[null,null,2,null,2,null,2,2]
[null,null,3,null,3,null,3,3,"Very low+very low+very low"]
[null,null,4,null,4,null,4,4,"Very low+very low+low"]
[null,null,5,null,5,null,5,5,"Very low+low+low"]
[null,null,6,null,6,null,6,6,"Low+low+low"]
[null,null,7,null,7,null,7,7,"Low+low+medium or very low+medium+medium"]
[null,null,8,null,8,null,8,8,"Low+low+high or very low+medium+high"]
[null,null,9,null,9,null,null,9,"Medium+medium+medium or very low+high+high or low+medium+high"]
[null,null,10,null,10,null,null,10,"High+medium+medium"]
[null,null,11,null,11,null,null,11,"High+high+medium"]
[null,null,12,null,12,null,null,12,"High+high+high"]
[null,null,13,null,13]
[null,null,14,null,14]
[null,null,15,null,15]
[null,null,16,null,16]
[null,null,17]
[null,null,18]
[null,null,19]
[null,null,20]